{"id":6367,"date":"2018-09-25T10:00:51","date_gmt":"2018-09-25T10:00:51","guid":{"rendered":"https:\/\/artefinalhq.com.br\/wp\/?p=6367"},"modified":"2018-09-25T09:55:42","modified_gmt":"2018-09-25T09:55:42","slug":"samurai-shiro-a-nova-graphic-novel-de-danilo-beyruth","status":"publish","type":"post","link":"https:\/\/artefinalhq.com.br\/wp\/2018\/09\/25\/samurai-shiro-a-nova-graphic-novel-de-danilo-beyruth\/","title":{"rendered":"Samurai Shir\u00f4, a nova graphic novel de Danilo Beyruth"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/artefinalhq.com.br\/wp\/wp-content\/uploads\/2018\/09\/Shirolanca_1.jpg\" alt=\"\" width=\"1080\" height=\"1080\" \/><\/p>\n<p>A DarkSide Books, por meio do seu selo DarkSide Graphic Novel, lan\u00e7ar\u00e1 em outubro (est\u00e1 em pr\u00e9-venda) o mais recente trabalho de <strong>Danilo Beyruth<\/strong>, a <em>graphic novel<\/em>\u00a0<em><strong>Samurai Shir\u00f4<\/strong><\/em>. A essa altura do campeonato, imagino que voc\u00ea j\u00e1 conhe\u00e7a e tenha lido ao menos um gibi do Beyruth (gravamos um <a href=\"https:\/\/artefinalhq.com.br\/wp\/2017\/05\/08\/os-7-jaguncos-da-derrota-12-the-evil-king\/\" target=\"_blank\" rel=\"noopener\"><strong>7 Jagun\u00e7os<\/strong><\/a>\u00a0cobrindo sua obra at\u00e9 aquele momento, maio de 2017). Desenhista da\u00a0Marvel, j\u00e1 colaborou com os <strong>Guardi\u00f5es da Gal\u00e1xia<\/strong>, <strong>Motoqueiro Fantasma<\/strong> e <strong>Cable<\/strong>; al\u00e9m disso, criou e publicou <em>Bando de Dois<\/em> e <em>Necronauta<\/em> e\u00a0emprestou o seu talento ao <strong>Astronauta<\/strong> de <strong>Mauricio de Sousa<\/strong>, numa trilogia de sucesso que inaugurou as <em>Graphics MSP<\/em>.<\/p>\n<p>Essa n\u00e3o \u00e9 a primeira parceria do autor com a editora. Danilo Beyruth foi o respons\u00e1vel pelas ilustra\u00e7\u00f5es e a capa da segunda e comemorativa edi\u00e7\u00e3o de <em>A Noite dos Mortos-Vivos<\/em>, de <strong>John Russo<\/strong>, lan\u00e7ado pela Darkside nesse ano (veja <a href=\"https:\/\/amzn.to\/2xyNb7i\" target=\"_blank\" rel=\"noopener\">aqui<\/a>). Agora, \u00e9 hora de publicar mais um trabalho autoral, uma HQ in\u00e9dita, misturando\u00a0m\u00e1fia, honra e sangue em S\u00e3o Paulo.<\/p>\n<p><em>Samurai Shir\u00f4<\/em> conta a hist\u00f3ria de lutas sangrentas pelo poder, honra familiar e do reencontro violento com o passado, vivido no agora por samurais modernos e a yakuza, a m\u00e1fia japonesa. A hist\u00f3ria se passa na Liberdade, bairro da regi\u00e3o central da cidade de S\u00e3o Paulo. <strong>Akemi<\/strong> \u00e9 uma jovem descendente de japoneses que v\u00ea surgir em seu caminho um estranho homem sem mem\u00f3ria, com uma katana, e passa a ser perseguida pelos yakuzas. Ela vai precisar enfrent\u00e1-los, assim como seu pr\u00f3prio passado, para sobreviver.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/artefinalhq.com.br\/wp\/wp-content\/uploads\/2018\/09\/Shirolanca_2.jpg\" alt=\"\" \/><\/p>\n<p>Quem conhece o trabalho de Danilo Beyruth talvez j\u00e1 tenha uma ideia do que esperar. A narrativa de <em>Samurai Shir\u00f4<\/em>, em ritmo veloz, \u00e9 repleta de a\u00e7\u00e3o e conversa com a intensidade e diversidade de S\u00e3o Paulo, para onde migraram milhares de orientais, e considerada a maior comunidade japonesa do mundo fora do Jap\u00e3o. A arte em preto e branco de Beyruth dialoga com os filmes de samurai do mestre <strong>Akira Kurosawa<\/strong>, diretor de cl\u00e1ssicos como <em>Yojimbo\u00a0<\/em>e <em>Sete Samurais<\/em>, al\u00e9m dos mang\u00e1s, como <em>Lobo Solit\u00e1rio<\/em>. Sem perder sua caracter\u00edstica, Beyruth se desafia a contar uma hist\u00f3ria dentro da tradi\u00e7\u00e3o de hist\u00f3rias de a\u00e7\u00e3o japonesas.<\/p>\n<p><em>Samurai Shir\u00f4<\/em> tem 192 p\u00e1ginas, capa dura, formato 17,5 x 26 cm e est\u00e1 custando R$ 59,90. Voc\u00ea pode encomendar o seu <a href=\"https:\/\/amzn.to\/2xxAMRi\" target=\"_blank\" rel=\"noopener\">AQUI<\/a>.<\/p>\n<p><center><br \/>\n<iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=artefinalhq-20&amp;marketplace=amazon&amp;region=BR&amp;placement=8594541392&amp;asins=8594541392&amp;linkId=8248ba0fa633f1b9109194a259c28116&amp;show_border=true&amp;link_opens_in_new_window=true&amp;price_color=333333&amp;title_color=0066c0&amp;bg_color=ffffff\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=artefinalhq-20&amp;marketplace=amazon&amp;region=BR&amp;placement=8560090266&amp;asins=8560090266&amp;linkId=11a2f78cf89bb6271799eb8ff03c0bb8&amp;show_border=true&amp;link_opens_in_new_window=true&amp;price_color=333333&amp;title_color=0066c0&amp;bg_color=ffffff\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=artefinalhq-20&amp;marketplace=amazon&amp;region=BR&amp;placement=856009069X&amp;asins=856009069X&amp;linkId=8692858d7d5f6a428b05d1d45c07e0f8&amp;show_border=true&amp;link_opens_in_new_window=true&amp;price_color=333333&amp;title_color=0066c0&amp;bg_color=ffffff\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=artefinalhq-20&amp;marketplace=amazon&amp;region=BR&amp;placement=8594540515&amp;asins=8594540515&amp;linkId=7891aa165b0185da618ba9200f527975&amp;show_border=true&amp;link_opens_in_new_window=true&amp;price_color=333333&amp;title_color=0066c0&amp;bg_color=ffffff\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=artefinalhq-20&amp;marketplace=amazon&amp;region=BR&amp;placement=8594540353&amp;asins=8594540353&amp;linkId=999add83620a25c9c76e2cdbc40d2cb7&amp;show_border=true&amp;link_opens_in_new_window=true&amp;price_color=333333&amp;title_color=0066c0&amp;bg_color=ffffff\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=artefinalhq-20&amp;marketplace=amazon&amp;region=BR&amp;placement=8594540469&amp;asins=8594540469&amp;linkId=609bf2949de4c2f0357bccceb7545d1d&amp;show_border=true&amp;link_opens_in_new_window=true&amp;price_color=333333&amp;title_color=0066c0&amp;bg_color=ffffff\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A DarkSide Books, por meio do seu selo DarkSide Graphic Novel, lan\u00e7ar\u00e1 em outubro (est\u00e1 em pr\u00e9-venda) o mais recente trabalho de Danilo Beyruth, a graphic novel\u00a0Samurai Shir\u00f4. A essa altura do campeonato, imagino que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"xn-wppe-expiration":[],"xn-wppe-expiration-action":[],"xn-wppe-expiration-prefix":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[117,931,609,930],"class_list":["post-6367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogpage","tag-danilo-beyruth","tag-darkside-books","tag-hq-nacional","tag-samurai-shiro"],"jetpack_featured_media_url":"https:\/\/artefinalhq.com.br\/wp\/wp-content\/uploads\/2018\/09\/Shirolanca_Destak.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/posts\/6367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/comments?post=6367"}],"version-history":[{"count":10,"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/posts\/6367\/revisions"}],"predecessor-version":[{"id":6411,"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/posts\/6367\/revisions\/6411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/media\/6383"}],"wp:attachment":[{"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/media?parent=6367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/categories?post=6367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artefinalhq.com.br\/wp\/wp-json\/wp\/v2\/tags?post=6367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}